{"id":5139,"date":"2019-12-25T22:38:58","date_gmt":"2019-12-25T21:38:58","guid":{"rendered":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707.jpg"},"modified":"2019-12-25T22:38:58","modified_gmt":"2019-12-25T21:38:58","slug":"20191221_131707-3","status":"inherit","type":"attachment","link":"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/","title":{"rendered":"20191221_131707"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-5139","attachment","type-attachment","status-inherit","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Claude MONHAROUL\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"G\u00eetes la cl\u00e9 des champs | G\u00eetes, chambres d&#039;h\u00f4tes de charme  en Bretagne\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"20191221_131707 | G\u00eetes la cl\u00e9 des champs\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-12-25T21:38:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-12-25T21:38:58+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"20191221_131707 | G\u00eetes la cl\u00e9 des champs\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/20191221_131707-3\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/20191221_131707-3\\\/#listItem\",\"name\":\"20191221_131707\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/20191221_131707-3\\\/#listItem\",\"position\":2,\"name\":\"20191221_131707\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/#listItem\",\"name\":\"Accueil\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/20191221_131707-3\\\/#itempage\",\"url\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/20191221_131707-3\\\/\",\"name\":\"20191221_131707 | G\\u00eetes la cl\\u00e9 des champs\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/20191221_131707-3\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/author\\\/claude\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/author\\\/claude\\\/#author\"},\"datePublished\":\"2019-12-25T22:38:58+01:00\",\"dateModified\":\"2019-12-25T22:38:58+01:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/#organization\",\"name\":\"G\\u00eetes la cl\\u00e9 des champs\",\"description\":\"G\\u00eetes, chambres d'h\\u00f4tes de charme  en Bretagne\",\"url\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/author\\\/claude\\\/#author\",\"url\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/author\\\/claude\\\/\",\"name\":\"Claude MONHAROUL\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/20191221_131707-3\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4e58826a91cd1c6766ec00ed1fe0d30c759f8620964bb2afdca521cf926a5f06?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Claude MONHAROUL\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/\",\"name\":\"G\\u00eetes la cl\\u00e9 des champs\",\"description\":\"G\\u00eetes, chambres d'h\\u00f4tes de charme  en Bretagne\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gites-lacledeschamps.fr\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"20191221_131707 | G\u00eetes la cl\u00e9 des champs","description":"","canonical_url":"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/#listItem","position":1,"name":"Accueil","item":"https:\/\/www.gites-lacledeschamps.fr\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/#listItem","name":"20191221_131707"}},{"@type":"ListItem","@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/#listItem","position":2,"name":"20191221_131707","previousItem":{"@type":"ListItem","@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/#listItem","name":"Accueil"}}]},{"@type":"ItemPage","@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/#itempage","url":"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/","name":"20191221_131707 | G\u00eetes la cl\u00e9 des champs","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/#breadcrumblist"},"author":{"@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/author\/claude\/#author"},"creator":{"@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/author\/claude\/#author"},"datePublished":"2019-12-25T22:38:58+01:00","dateModified":"2019-12-25T22:38:58+01:00"},{"@type":"Organization","@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/#organization","name":"G\u00eetes la cl\u00e9 des champs","description":"G\u00eetes, chambres d'h\u00f4tes de charme  en Bretagne","url":"https:\/\/www.gites-lacledeschamps.fr\/en\/"},{"@type":"Person","@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/author\/claude\/#author","url":"https:\/\/www.gites-lacledeschamps.fr\/en\/author\/claude\/","name":"Claude MONHAROUL","image":{"@type":"ImageObject","@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/4e58826a91cd1c6766ec00ed1fe0d30c759f8620964bb2afdca521cf926a5f06?s=96&d=mm&r=g","width":96,"height":96,"caption":"Claude MONHAROUL"}},{"@type":"WebSite","@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/#website","url":"https:\/\/www.gites-lacledeschamps.fr\/en\/","name":"G\u00eetes la cl\u00e9 des champs","description":"G\u00eetes, chambres d'h\u00f4tes de charme  en Bretagne","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.gites-lacledeschamps.fr\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"G\u00eetes la cl\u00e9 des champs | G\u00eetes, chambres d'h\u00f4tes de charme  en Bretagne","og:type":"article","og:title":"20191221_131707 | G\u00eetes la cl\u00e9 des champs","og:url":"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/","article:published_time":"2019-12-25T21:38:58+00:00","article:modified_time":"2019-12-25T21:38:58+00:00","twitter:card":"summary","twitter:title":"20191221_131707 | G\u00eetes la cl\u00e9 des champs"},"aioseo_meta_data":{"post_id":"5139","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-06-10 15:07:05","updated":"2025-06-10 15:07:05","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.gites-lacledeschamps.fr\/en\/\" title=\"Accueil\">Accueil<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t20191221_131707\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Accueil","link":"https:\/\/www.gites-lacledeschamps.fr\/en\/"},{"label":"20191221_131707","link":"https:\/\/www.gites-lacledeschamps.fr\/en\/20191221_131707-3\/"}],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-225x300.jpg 225w, https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-768x1024.jpg 768w, https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-773x1030.jpg 773w, https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-529x705.jpg 529w, https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-450x600.jpg 450w, https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707.jpg 808w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":808,"height":1077,"file":"2019\/12\/20191221_131707.jpg","sizes":{"thumbnail":{"file":"20191221_131707-80x80.jpg","width":80,"height":80,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-80x80.jpg"},"medium":{"file":"20191221_131707-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-225x300.jpg"},"medium_large":{"file":"20191221_131707-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-768x1024.jpg"},"large":{"file":"20191221_131707-773x1030.jpg","width":773,"height":1030,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-773x1030.jpg"},"widget":{"file":"20191221_131707-36x36.jpg","width":36,"height":36,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-36x36.jpg"},"square":{"file":"20191221_131707-180x180.jpg","width":180,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-180x180.jpg"},"featured":{"file":"20191221_131707-808x430.jpg","width":808,"height":430,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-808x430.jpg"},"featured_large":{"file":"20191221_131707-808x630.jpg","width":808,"height":630,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-808x630.jpg"},"portfolio":{"file":"20191221_131707-495x400.jpg","width":495,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-495x400.jpg"},"portfolio_small":{"file":"20191221_131707-260x185.jpg","width":260,"height":185,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-260x185.jpg"},"gallery":{"file":"20191221_131707-808x684.jpg","width":808,"height":684,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-808x684.jpg"},"magazine":{"file":"20191221_131707-710x375.jpg","width":710,"height":375,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-710x375.jpg"},"masonry":{"file":"20191221_131707-529x705.jpg","width":529,"height":705,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-529x705.jpg"},"entry_with_sidebar":{"file":"20191221_131707-808x321.jpg","width":808,"height":321,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-808x321.jpg"},"entry_without_sidebar":{"file":"20191221_131707-808x423.jpg","width":808,"height":423,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-808x423.jpg"},"shop_thumbnail":{"file":"20191221_131707-120x120.jpg","width":120,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-120x120.jpg"},"shop_catalog":{"file":"20191221_131707-450x450.jpg","width":450,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-450x450.jpg"},"shop_single":{"file":"20191221_131707-450x600.jpg","width":450,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707-450x600.jpg"},"full":{"file":"20191221_131707.jpg","width":808,"height":1077,"mime_type":"image\/jpeg","source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.gites-lacledeschamps.fr\/wp-content\/uploads\/2019\/12\/20191221_131707.jpg","_links":{"self":[{"href":"https:\/\/www.gites-lacledeschamps.fr\/en\/wp-json\/wp\/v2\/media\/5139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gites-lacledeschamps.fr\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.gites-lacledeschamps.fr\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.gites-lacledeschamps.fr\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gites-lacledeschamps.fr\/en\/wp-json\/wp\/v2\/comments?post=5139"}]}}